{"id":168,"count":41,"description":"","link":"https:\/\/www.arcoabogados.es\/en\/category\/legal-en","name":"Legal","slug":"legal-en","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Legal Archives - ARCO Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arcoabogados.es\/en\/category\/legal-en\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Legal Archives - ARCO Abogados\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arcoabogados.es\/en\/category\/legal-en\" \/>\n<meta property=\"og:site_name\" content=\"ARCO Abogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/en\\\/category\\\/legal-en\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/en\\\/category\\\/legal-en\",\"name\":\"Legal Archives - ARCO Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/en#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/en\\\/category\\\/legal-en#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/en\\\/category\\\/legal-en#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.arcoabogados.es\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/en#website\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/en\",\"name\":\"ARCO Abogados\",\"description\":\"Leading Tax and Legal Practice in Spain\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/en#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arcoabogados.es\\\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/en#organization\",\"name\":\"ARCO Abogados\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/en#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/arco-logo-160px.png\",\"contentUrl\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/arco-logo-160px.png\",\"width\":160,\"height\":42,\"caption\":\"ARCO Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/en#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arcoabogados\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Legal Archives - ARCO Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arcoabogados.es\/en\/category\/legal-en","og_locale":"en_US","og_type":"article","og_title":"Legal Archives - ARCO Abogados","og_url":"https:\/\/www.arcoabogados.es\/en\/category\/legal-en","og_site_name":"ARCO Abogados","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.arcoabogados.es\/en\/category\/legal-en","url":"https:\/\/www.arcoabogados.es\/en\/category\/legal-en","name":"Legal Archives - ARCO Abogados","isPartOf":{"@id":"https:\/\/www.arcoabogados.es\/en#website"},"breadcrumb":{"@id":"https:\/\/www.arcoabogados.es\/en\/category\/legal-en#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.arcoabogados.es\/en\/category\/legal-en#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.arcoabogados.es\/en"},{"@type":"ListItem","position":2,"name":"Legal"}]},{"@type":"WebSite","@id":"https:\/\/www.arcoabogados.es\/en#website","url":"https:\/\/www.arcoabogados.es\/en","name":"ARCO Abogados","description":"Leading Tax and Legal Practice in Spain","publisher":{"@id":"https:\/\/www.arcoabogados.es\/en#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arcoabogados.es\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arcoabogados.es\/en#organization","name":"ARCO Abogados","url":"https:\/\/www.arcoabogados.es\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arcoabogados.es\/en#\/schema\/logo\/image\/","url":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2023\/07\/arco-logo-160px.png","contentUrl":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2023\/07\/arco-logo-160px.png","width":160,"height":42,"caption":"ARCO Abogados"},"image":{"@id":"https:\/\/www.arcoabogados.es\/en#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/arcoabogados\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.arcoabogados.es\/en\/wp-json\/wp\/v2\/categories\/168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arcoabogados.es\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.arcoabogados.es\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.arcoabogados.es\/en\/wp-json\/wp\/v2\/posts?categories=168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}