{"id":12928,"date":"2024-10-15T13:59:46","date_gmt":"2024-10-15T11:59:46","guid":{"rendered":"https:\/\/www.arcoabogados.es\/?p=12928"},"modified":"2024-10-17T12:37:10","modified_gmt":"2024-10-17T10:37:10","slug":"ii-congres-aranzadi-dadvocacia-in-house","status":"publish","type":"post","link":"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house","title":{"rendered":"II Congr\u00e9s Aranzadi d\u00b4Advocacia In House"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ens complau presentar-los el <strong>II Congr\u00e9s&nbsp;Aranzadi&nbsp;d&#8217;Advocacia&nbsp;In&nbsp;House<\/strong>, en el qual ARCO Abogados y Asesores Tributarios participa, amb el prop\u00f2sit de crear un marc d&#8217;intercanvi i coneixement per al dret dels negocis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La nostra intervenci\u00f3 tractar\u00e0 sobre:<\/strong> Contractaci\u00f3 p\u00fablica i Empreses Licitadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pr\u00f2rrogues dels contractes p\u00fablics.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Problem\u00e0tica actual de les pr\u00f2rrogues de contractes de serveis. <\/li>\n\n\n\n<li>Qu\u00e8 pot fa el contractista davant la imposici\u00f3 per l&#8217;Administraci\u00f3 d&#8217;una pr\u00f2rroga de car\u00e0cter antiecon\u00f2mic?<\/li>\n\n\n\n<li>Qu\u00e8 pot\/ha de fer l&#8217;Administraci\u00f3 per a evitar que les pr\u00f2rrogues tinguin car\u00e0cter antiecon\u00f2mic?<\/li>\n\n\n\n<li>Interpretaci\u00f3 de l&#8217;article 29.2 de la&nbsp;LCSP.<\/li>\n\n\n\n<li>Distinci\u00f3 entre pr\u00f2rrogues contractuals i pr\u00f2rrogues for\u00e7oses.<\/li>\n\n\n\n<li>Retribuci\u00f3 dels contractistes durant les pr\u00f2rrogues for\u00e7oses.<\/li>\n\n\n\n<li>Especificitats de les pr\u00f2rrogues de contractes de concessi\u00f3 de serveis p\u00fablics.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Modalitats de presentacions d&#8217;ofertes conjuntes.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>UTE, integraci\u00f3 de mitjans aliens, subcontractaci\u00f3. Quan han d&#8217;utilitzar-se cadascuna d&#8217;aquestes figures?<\/li>\n\n\n\n<li>Han caigut les&nbsp;UTEs&nbsp;en desgr\u00e0cia? El mal \u00fas de les&nbsp;UTEs&nbsp;en relaci\u00f3 amb el Dret de la Compet\u00e8ncia.<\/li>\n\n\n\n<li>L\u00edmits a la figura de la integraci\u00f3 de mitjans aliens. Quan i fins a on ha d&#8217;utilitzar-se?<\/li>\n\n\n\n<li>Quan pot rec\u00f3rrer-se a la subcontractaci\u00f3? Problemes espec\u00edfics derivats de la subcontractaci\u00f3.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Dirigeix i modera la taula:&nbsp;<strong>Roger Canals Vaquer.<\/strong> Responsable de l&#8217;\u00c0rea de Contractaci\u00f3 P\u00fablica d&#8217;ARCO ABOGADOS Y ASESORES TRIBUTARIOS, S.L.P.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Membres de la taula:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Elena&nbsp;Hern\u00e1ez&nbsp;Salguero<\/strong>. Consellera en el Tribunal de Comptes d&#8217;Espanya.<\/li>\n\n\n\n<li><strong>Francisco A. Bravo&nbsp;Virumbrales<\/strong>. Subdirector General del Consultiu. Advocacia General de la Comunitat de Madrid.<\/li>\n\n\n\n<li><strong>Francisco de Borja Rodr\u00edguez Garc\u00eda<\/strong>. Director Corporatiu d&#8217;Assessoria Jur\u00eddica en Grup&nbsp;Azvi.<\/li>\n\n\n\n<li><strong>Ana Garc\u00eda&nbsp;Gimenez<\/strong>. Advocada, \u00e0rea Jur\u00eddica&nbsp;Sorigu\u00e9.<\/li>\n\n\n\n<li><strong>Mar\u00eda Pilar Garc\u00eda Cruz<\/strong>. Advocada en&nbsp;cap&nbsp;(e.f.).&nbsp;Assessoria&nbsp;Jur\u00eddica.&nbsp;Departament&nbsp;de&nbsp;Territori,&nbsp;Habitatge&nbsp;i&nbsp;Transici\u00f3&nbsp;Ecol\u00f2gica.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El II Congr\u00e9s&nbsp;Aranzadi&nbsp;de Dret dels Negocis es celebrar\u00e0 els dies <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-awb-color-6-color\"><strong>19 i 20 de novembre de 2024<\/strong><\/mark>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La seu ser\u00e0 a MADRID, a l&#8217;Auditori i Salas&nbsp;SM&nbsp;Begu\u00e9&nbsp;i&nbsp;JG&nbsp;Berlanga, La Caja de M\u00fasica. Plaza de Cibeles 1. Un espai c\u00e8ntric, amb atractiu hist\u00f2ric-cultural i dotat de tots els mitjans.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.congreso-aranzadi-abogados-in-house.es\/\">M\u00e9s informaci\u00f3<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si li interessa assistir al Congr\u00e9s,&nbsp;pot contactar-nos a trav\u00e9s del correu: congresoaranzadi@arcoabogados.es<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.congreso-aranzadi-abogados-in-house.es\/\"><img decoding=\"async\" width=\"1024\" height=\"77\" data-src=\"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/10\/ES-Banner_II-Congreso-Inhouse_1200x90-1024x77.png\" alt=\"\" class=\"wp-image-12864 lazyload\" data-srcset=\"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/10\/ES-Banner_II-Congreso-Inhouse_1200x90-200x15.png 200w, https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/10\/ES-Banner_II-Congreso-Inhouse_1200x90-300x23.png 300w, https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/10\/ES-Banner_II-Congreso-Inhouse_1200x90-400x30.png 400w, https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/10\/ES-Banner_II-Congreso-Inhouse_1200x90-600x45.png 600w, https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/10\/ES-Banner_II-Congreso-Inhouse_1200x90-768x58.png 768w, https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/10\/ES-Banner_II-Congreso-Inhouse_1200x90-800x60.png 800w, https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/10\/ES-Banner_II-Congreso-Inhouse_1200x90-1024x77.png 1024w, https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/10\/ES-Banner_II-Congreso-Inhouse_1200x90.png 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/77;\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ens complau presentar-los el II Congr\u00e9s&nbsp;Aranzadi&nbsp;d&#8217;Advocacia&nbsp;In&nbsp;House, en el qual ARCO<\/p>\n","protected":false},"author":12,"featured_media":12923,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[322],"tags":[],"class_list":["post-12928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legal-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>II Congr\u00e9s Aranzadi d\u00b4Advocacia In House - ARCO Abogados<\/title>\n<meta name=\"description\" content=\"Ens complau presentar-los el II Congr\u00e9s&nbsp;Aranzadi&nbsp;d&#039;Advocacia&nbsp;In&nbsp;House, en el qual ARCO Abogados y Asesores Tributarios participa, amb\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"II Congr\u00e9s Aranzadi d\u00b4Advocacia In House - ARCO Abogados\" \/>\n<meta property=\"og:description\" content=\"Ens complau presentar-los el II Congr\u00e9s&nbsp;Aranzadi&nbsp;d&#039;Advocacia&nbsp;In&nbsp;House, en el qual ARCO Abogados y Asesores Tributarios participa, amb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house\" \/>\n<meta property=\"og:site_name\" content=\"ARCO Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-15T11:59:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-17T10:37:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/10\/Diseno-sin-titulo-5-1024x512.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Anna Vivas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/ii-congres-aranzadi-dadvocacia-in-house#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/ii-congres-aranzadi-dadvocacia-in-house\"},\"author\":{\"name\":\"Anna Vivas\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#\\\/schema\\\/person\\\/8c38bf10d19f9bf1eedff598c01ce056\"},\"headline\":\"II Congr\u00e9s Aranzadi d\u00b4Advocacia In House\",\"datePublished\":\"2024-10-15T11:59:46+00:00\",\"dateModified\":\"2024-10-17T10:37:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/ii-congres-aranzadi-dadvocacia-in-house\"},\"wordCount\":425,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/ii-congres-aranzadi-dadvocacia-in-house#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Diseno-sin-titulo-5.png\",\"articleSection\":[\"Legal\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/ii-congres-aranzadi-dadvocacia-in-house\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/ii-congres-aranzadi-dadvocacia-in-house\",\"name\":\"II Congr\u00e9s Aranzadi d\u00b4Advocacia In House - ARCO Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/ii-congres-aranzadi-dadvocacia-in-house#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/ii-congres-aranzadi-dadvocacia-in-house#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Diseno-sin-titulo-5.png\",\"datePublished\":\"2024-10-15T11:59:46+00:00\",\"dateModified\":\"2024-10-17T10:37:10+00:00\",\"description\":\"Ens complau presentar-los el II Congr\u00e9s&nbsp;Aranzadi&nbsp;d'Advocacia&nbsp;In&nbsp;House, en el qual ARCO Abogados y Asesores Tributarios participa, amb\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/ii-congres-aranzadi-dadvocacia-in-house#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/ii-congres-aranzadi-dadvocacia-in-house\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/ii-congres-aranzadi-dadvocacia-in-house#primaryimage\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Diseno-sin-titulo-5.png\",\"contentUrl\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Diseno-sin-titulo-5.png\",\"width\":6000,\"height\":3000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/ii-congres-aranzadi-dadvocacia-in-house#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/inici\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"II Congr\u00e9s Aranzadi d\u00b4Advocacia In House\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#website\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\",\"name\":\"ARCO Abogados\",\"description\":\"Leading Tax and Legal Practice in Spain\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#organization\",\"name\":\"ARCO Abogados\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/arco-logo-160px.png\",\"contentUrl\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/arco-logo-160px.png\",\"width\":160,\"height\":42,\"caption\":\"ARCO Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arcoabogados\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#\\\/schema\\\/person\\\/8c38bf10d19f9bf1eedff598c01ce056\",\"name\":\"Anna Vivas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g\",\"caption\":\"Anna Vivas\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"II Congr\u00e9s Aranzadi d\u00b4Advocacia In House - ARCO Abogados","description":"Ens complau presentar-los el II Congr\u00e9s&nbsp;Aranzadi&nbsp;d'Advocacia&nbsp;In&nbsp;House, en el qual ARCO Abogados y Asesores Tributarios participa, amb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house","og_locale":"ca_ES","og_type":"article","og_title":"II Congr\u00e9s Aranzadi d\u00b4Advocacia In House - ARCO Abogados","og_description":"Ens complau presentar-los el II Congr\u00e9s&nbsp;Aranzadi&nbsp;d'Advocacia&nbsp;In&nbsp;House, en el qual ARCO Abogados y Asesores Tributarios participa, amb","og_url":"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house","og_site_name":"ARCO Abogados","article_published_time":"2024-10-15T11:59:46+00:00","article_modified_time":"2024-10-17T10:37:10+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/10\/Diseno-sin-titulo-5-1024x512.png","type":"image\/png"}],"author":"Anna Vivas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house#article","isPartOf":{"@id":"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house"},"author":{"name":"Anna Vivas","@id":"https:\/\/www.arcoabogados.es\/ca#\/schema\/person\/8c38bf10d19f9bf1eedff598c01ce056"},"headline":"II Congr\u00e9s Aranzadi d\u00b4Advocacia In House","datePublished":"2024-10-15T11:59:46+00:00","dateModified":"2024-10-17T10:37:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house"},"wordCount":425,"publisher":{"@id":"https:\/\/www.arcoabogados.es\/ca#organization"},"image":{"@id":"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house#primaryimage"},"thumbnailUrl":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/10\/Diseno-sin-titulo-5.png","articleSection":["Legal"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house","url":"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house","name":"II Congr\u00e9s Aranzadi d\u00b4Advocacia In House - ARCO Abogados","isPartOf":{"@id":"https:\/\/www.arcoabogados.es\/ca#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house#primaryimage"},"image":{"@id":"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house#primaryimage"},"thumbnailUrl":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/10\/Diseno-sin-titulo-5.png","datePublished":"2024-10-15T11:59:46+00:00","dateModified":"2024-10-17T10:37:10+00:00","description":"Ens complau presentar-los el II Congr\u00e9s&nbsp;Aranzadi&nbsp;d'Advocacia&nbsp;In&nbsp;House, en el qual ARCO Abogados y Asesores Tributarios participa, amb","breadcrumb":{"@id":"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house#primaryimage","url":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/10\/Diseno-sin-titulo-5.png","contentUrl":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/10\/Diseno-sin-titulo-5.png","width":6000,"height":3000},{"@type":"BreadcrumbList","@id":"https:\/\/www.arcoabogados.es\/ca\/ii-congres-aranzadi-dadvocacia-in-house#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.arcoabogados.es\/ca\/inici"},{"@type":"ListItem","position":2,"name":"II Congr\u00e9s Aranzadi d\u00b4Advocacia In House"}]},{"@type":"WebSite","@id":"https:\/\/www.arcoabogados.es\/ca#website","url":"https:\/\/www.arcoabogados.es\/ca","name":"ARCO Abogados","description":"Leading Tax and Legal Practice in Spain","publisher":{"@id":"https:\/\/www.arcoabogados.es\/ca#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arcoabogados.es\/ca?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.arcoabogados.es\/ca#organization","name":"ARCO Abogados","url":"https:\/\/www.arcoabogados.es\/ca","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.arcoabogados.es\/ca#\/schema\/logo\/image\/","url":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2023\/07\/arco-logo-160px.png","contentUrl":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2023\/07\/arco-logo-160px.png","width":160,"height":42,"caption":"ARCO Abogados"},"image":{"@id":"https:\/\/www.arcoabogados.es\/ca#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/arcoabogados\/"]},{"@type":"Person","@id":"https:\/\/www.arcoabogados.es\/ca#\/schema\/person\/8c38bf10d19f9bf1eedff598c01ce056","name":"Anna Vivas","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g","caption":"Anna Vivas"}}]}},"_links":{"self":[{"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/posts\/12928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/comments?post=12928"}],"version-history":[{"count":6,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/posts\/12928\/revisions"}],"predecessor-version":[{"id":12938,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/posts\/12928\/revisions\/12938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/media\/12923"}],"wp:attachment":[{"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/media?parent=12928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/categories?post=12928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/tags?post=12928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}