{"id":12464,"date":"2024-09-23T13:14:10","date_gmt":"2024-09-23T11:14:10","guid":{"rendered":"https:\/\/www.arcoabogados.es\/?p=12464"},"modified":"2024-09-23T13:39:58","modified_gmt":"2024-09-23T11:39:58","slug":"prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis","status":"publish","type":"post","link":"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis","title":{"rendered":"Pr\u00f3rrogues contractuals i increment dels costos d\u00b4execuci\u00f3 de contractes p\u00fablics de serveis"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Despr\u00e9s que, durant la segona d\u00e8cada del segle en curs, ens hagu\u00e9ssim acostumat a unes taxes d&#8217;inflaci\u00f3 planes o molt disminu\u00efdes, en la postpand\u00e8mia (especialment durant el per\u00edode 2021 \u2013 2023), va esclatar un episodi inflacionari, aconseguint l&#8217;increment del cost dels b\u00e9ns de consum i dels factors de producci\u00f3 cotes que nom\u00e9s recordem els ara anomenats \u201cboomers\u201d. En l&#8217;\u00e0mbit de la contractaci\u00f3 p\u00fablica, aquest fenomen ens ha obligat, d&#8217;una banda, a desempolsar conceptes jur\u00eddics que ja cr\u00e8iem traspassats a millor vida (per exemple, la revisi\u00f3 de preus), o b\u00e9, a topar-nos amb fen\u00f2mens ignots i impensables fa tan sols uns anys, com les retic\u00e8ncies, o directament la ren\u00fancia, de contractistes a l&#8217;execuci\u00f3 de pr\u00f2rrogues contractuals o a adjudicacions de contractes que esdevenen antiecon\u00f2mics amb el pas de tot just mesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aquest fenomen, juntament amb altres lligats a la prolongaci\u00f3 dels contractes p\u00fablics de serveis (sense anar m\u00e9s lluny, les pr\u00f2rrogues for\u00e7oses imposades als contractistes en cas de retards en les licitacions de nous contractes, o d&#8217;impugnaci\u00f3 davant els Tribunals de Contractaci\u00f3 d&#8217;actes del procediment de licitaci\u00f3), han convertit a les pr\u00f2rrogues dels contractes p\u00fablics de serveis en material inflamable, d&#8217;alta litigiositat.<br><br>La problem\u00e0tica \u00e9s especialment apressant en els contractes de serveis que van ser licitats (i, per tant, pressupostats i dimensionats), just abans del per\u00edode inflacionari iniciat en el primer trimestre de 2021 (i que ara estan aconseguit el final del seu per\u00edode de vig\u00e8ncia). I aix\u00f2, ja que el dimensionament econ\u00f2mic d&#8217;aquests contractes ha quedat superat per la realitat, fent aix\u00f2 que la prestaci\u00f3 dels serveis pels contractistes p\u00fablics sigui antiecon\u00f2mica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tot aix\u00f2 sumeix als contractistes p\u00fablics en una delicada tessitura, at\u00e8s que l&#8217;execuci\u00f3 de les pr\u00f2rrogues d&#8217;aquests contractes (ja siguin previstes en els plecs, o pr\u00f2rrogues for\u00e7oses imposades per l&#8217;Administraci\u00f3 per causes sobrevingudes), pot tenir conseq\u00fc\u00e8ncies econ\u00f2miques ru\u00efnoses. I, al seu torn, la ren\u00fancia a l&#8217;execuci\u00f3 de pr\u00f2rrogues b\u00e9 sigui previstes contractualment o for\u00e7adament imposades per l&#8217;Administraci\u00f3, pot arribar a tenir severes conseq\u00fc\u00e8ncies per als contractistes, des de la imposici\u00f3 de penalitzacions econ\u00f2miques (en el millor dels casos) fins a prohibicions de contractar (en el pitjor).<br><br>Davant la tessitura de la imposici\u00f3 d&#8217;una pr\u00f2rroga manifestament antiecon\u00f2mica, ha de resignar-se el contractista a executar-la als preus contractuals inicials, i amb aix\u00f2, a suportar una p\u00e8rdua econ\u00f2mica? o existeixen en la nostra normativa mecanismes que puguin permetre al contractista b\u00e9 no executar una pr\u00f2rroga, o b\u00e9 percebre el cost real dels serveis prestats?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Racons poc transitats i\/o coneguts de l&#8217;actual Llei de Contractes del Sector P\u00fablic (Llei 9\/2017, de 8 de novembre), permeten als contractistes adoptar, davant la perspectiva de la imposici\u00f3 per l&#8217;Administraci\u00f3 d&#8217;una pr\u00f2rroga antiecon\u00f2mica, una actitud m\u00e9s edificant que la mera resignaci\u00f3 cristiana. Conegut \u00e9s que l&#8217;article 29.4 de la&nbsp;LCSP&nbsp;autoritza l&#8217;Administraci\u00f3 a prolongar l&#8217;aplicaci\u00f3 dels preus del contracte per nou mesos en cas de pr\u00f2rroga for\u00e7osa d&#8217;aquest, sempre que l&#8217;Administraci\u00f3 hagu\u00e9s publicat l&#8217;anunci de licitaci\u00f3 del contracte substitutori abans dels tres mesos anteriors a la finalitzaci\u00f3 del contracte prorrogat. Aix\u00f2 comporta, impl\u00edcitament, que l&#8217;Administraci\u00f3 haur\u00e0 d&#8217;aplicar preus nous, o b\u00e9 des de l&#8217;inici de la pr\u00f2rroga for\u00e7osa (si no ha licitat amb l&#8217;antelaci\u00f3 requerida), o ben transcorreguts nou mesos des de l&#8217;inici de la pr\u00f2rroga (si ha licitat quan devia). El potencial litigi se centra aqu\u00ed en quins preus nous hauran d&#8217;aplicar-se, que, per mandat de l&#8217;article 102.3 de la&nbsp;LCSP&nbsp;haurien de correspondre&#8217;s amb els de mercat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstant aix\u00f2, el \u201csant greal\u201d que encara est\u00e0 per explotar \u00e9s, al nostre judici, la previsi\u00f3 continguda en l&#8217;article 29.2 de la&nbsp;LCSP, segons la qual \u201cEl contracte podr\u00e0 preveure una o diverses pr\u00f2rrogues sempre que les seves caracter\u00edstiques romanguin inalterables durant el per\u00edode de durada d&#8217;aquestes\u201d. Qu\u00e8 ha d&#8217;entendre&#8217;s per condicions \u201cinalterades\u201d que permetin l&#8217;execuci\u00f3 de les pr\u00f2rrogues contractualment previstes? En una interpretaci\u00f3 \u00e0mplia, el precepte hauria de possibilitar la no execuci\u00f3 de les pr\u00f2rrogues d&#8217;aquells contractes en els quals, durant el seu per\u00edode inicial de vig\u00e8ncia, s&#8217;hagi produ\u00eft un desequilibri de les prestacions per causes alienes al contractista (com, per exemple, un increment imprevisible dels factors de producci\u00f3 que facin econ\u00f2micament inviable l&#8217;execuci\u00f3 del contracte).<br><br>Aix\u00ed doncs, sembla que hi ha alternatives a la resignaci\u00f3. Nom\u00e9s falta atrevir-se a explorar-les.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/09\/contractacio-publica-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustaci\u00f3 del fitxer contractaci\u00f3 publica (1).\"><\/object><a id=\"wp-block-file--media-25742b35-9256-41d9-9923-577a7c7ae027\" href=\"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/09\/contractacio-publica-1.pdf\">contractaci\u00f3 publica (1)<\/a><a href=\"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/09\/contractacio-publica-1.pdf\" class=\"fusion-button-default fusion-button-default-size wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-25742b35-9256-41d9-9923-577a7c7ae027\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Despr\u00e9s que, durant la segona d\u00e8cada del segle en curs,<\/p>\n","protected":false},"author":12,"featured_media":12460,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[322],"tags":[397],"class_list":["post-12464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legal-ca","tag-contratacion-publica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr\u00f3rrogues contractuals i increment dels costos d\u00b4execuci\u00f3 de contractes p\u00fablics de serveis - ARCO Abogados<\/title>\n<meta name=\"description\" content=\"Despr\u00e9s que, durant la segona d\u00e8cada del segle en curs, ens hagu\u00e9ssim acostumat a unes taxes d&#039;inflaci\u00f3 planes o molt disminu\u00efdes, en la postpand\u00e8mia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00f3rrogues contractuals i increment dels costos d\u00b4execuci\u00f3 de contractes p\u00fablics de serveis - ARCO Abogados\" \/>\n<meta property=\"og:description\" content=\"Despr\u00e9s que, durant la segona d\u00e8cada del segle en curs, ens hagu\u00e9ssim acostumat a unes taxes d&#039;inflaci\u00f3 planes o molt disminu\u00efdes, en la postpand\u00e8mia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis\" \/>\n<meta property=\"og:site_name\" content=\"ARCO Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-23T11:14:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-23T11:39:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/09\/gonz-ddl-kcgo1d8Xd9Q-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anna Vivas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis\"},\"author\":{\"name\":\"Anna Vivas\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#\\\/schema\\\/person\\\/8c38bf10d19f9bf1eedff598c01ce056\"},\"headline\":\"Pr\u00f3rrogues contractuals i increment dels costos d\u00b4execuci\u00f3 de contractes p\u00fablics de serveis\",\"datePublished\":\"2024-09-23T11:14:10+00:00\",\"dateModified\":\"2024-09-23T11:39:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis\"},\"wordCount\":780,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/gonz-ddl-kcgo1d8Xd9Q-unsplash-scaled.jpg\",\"keywords\":[\"contrataci\u00f3n p\u00fablica\"],\"articleSection\":[\"Legal\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis\",\"name\":\"Pr\u00f3rrogues contractuals i increment dels costos d\u00b4execuci\u00f3 de contractes p\u00fablics de serveis - ARCO Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/gonz-ddl-kcgo1d8Xd9Q-unsplash-scaled.jpg\",\"datePublished\":\"2024-09-23T11:14:10+00:00\",\"dateModified\":\"2024-09-23T11:39:58+00:00\",\"description\":\"Despr\u00e9s que, durant la segona d\u00e8cada del segle en curs, ens hagu\u00e9ssim acostumat a unes taxes d'inflaci\u00f3 planes o molt disminu\u00efdes, en la postpand\u00e8mia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis#primaryimage\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/gonz-ddl-kcgo1d8Xd9Q-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/gonz-ddl-kcgo1d8Xd9Q-unsplash-scaled.jpg\",\"width\":1440,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/inici\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr\u00f3rrogues contractuals i increment dels costos d\u00b4execuci\u00f3 de contractes p\u00fablics de serveis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#website\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\",\"name\":\"ARCO Abogados\",\"description\":\"Leading Tax and Legal Practice in Spain\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#organization\",\"name\":\"ARCO Abogados\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/arco-logo-160px.png\",\"contentUrl\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/arco-logo-160px.png\",\"width\":160,\"height\":42,\"caption\":\"ARCO Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arcoabogados\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#\\\/schema\\\/person\\\/8c38bf10d19f9bf1eedff598c01ce056\",\"name\":\"Anna Vivas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g\",\"caption\":\"Anna Vivas\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00f3rrogues contractuals i increment dels costos d\u00b4execuci\u00f3 de contractes p\u00fablics de serveis - ARCO Abogados","description":"Despr\u00e9s que, durant la segona d\u00e8cada del segle en curs, ens hagu\u00e9ssim acostumat a unes taxes d'inflaci\u00f3 planes o molt disminu\u00efdes, en la postpand\u00e8mia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis","og_locale":"ca_ES","og_type":"article","og_title":"Pr\u00f3rrogues contractuals i increment dels costos d\u00b4execuci\u00f3 de contractes p\u00fablics de serveis - ARCO Abogados","og_description":"Despr\u00e9s que, durant la segona d\u00e8cada del segle en curs, ens hagu\u00e9ssim acostumat a unes taxes d'inflaci\u00f3 planes o molt disminu\u00efdes, en la postpand\u00e8mia","og_url":"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis","og_site_name":"ARCO Abogados","article_published_time":"2024-09-23T11:14:10+00:00","article_modified_time":"2024-09-23T11:39:58+00:00","og_image":[{"width":1440,"height":1920,"url":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/09\/gonz-ddl-kcgo1d8Xd9Q-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Anna Vivas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis#article","isPartOf":{"@id":"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis"},"author":{"name":"Anna Vivas","@id":"https:\/\/www.arcoabogados.es\/ca#\/schema\/person\/8c38bf10d19f9bf1eedff598c01ce056"},"headline":"Pr\u00f3rrogues contractuals i increment dels costos d\u00b4execuci\u00f3 de contractes p\u00fablics de serveis","datePublished":"2024-09-23T11:14:10+00:00","dateModified":"2024-09-23T11:39:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis"},"wordCount":780,"publisher":{"@id":"https:\/\/www.arcoabogados.es\/ca#organization"},"image":{"@id":"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis#primaryimage"},"thumbnailUrl":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/09\/gonz-ddl-kcgo1d8Xd9Q-unsplash-scaled.jpg","keywords":["contrataci\u00f3n p\u00fablica"],"articleSection":["Legal"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis","url":"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis","name":"Pr\u00f3rrogues contractuals i increment dels costos d\u00b4execuci\u00f3 de contractes p\u00fablics de serveis - ARCO Abogados","isPartOf":{"@id":"https:\/\/www.arcoabogados.es\/ca#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis#primaryimage"},"image":{"@id":"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis#primaryimage"},"thumbnailUrl":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/09\/gonz-ddl-kcgo1d8Xd9Q-unsplash-scaled.jpg","datePublished":"2024-09-23T11:14:10+00:00","dateModified":"2024-09-23T11:39:58+00:00","description":"Despr\u00e9s que, durant la segona d\u00e8cada del segle en curs, ens hagu\u00e9ssim acostumat a unes taxes d'inflaci\u00f3 planes o molt disminu\u00efdes, en la postpand\u00e8mia","breadcrumb":{"@id":"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis#primaryimage","url":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/09\/gonz-ddl-kcgo1d8Xd9Q-unsplash-scaled.jpg","contentUrl":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/09\/gonz-ddl-kcgo1d8Xd9Q-unsplash-scaled.jpg","width":1440,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.arcoabogados.es\/ca\/prorrogues-contractuals-i-increment-dels-costos-dexecucio-de-contractes-publics-de-serveis#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.arcoabogados.es\/ca\/inici"},{"@type":"ListItem","position":2,"name":"Pr\u00f3rrogues contractuals i increment dels costos d\u00b4execuci\u00f3 de contractes p\u00fablics de serveis"}]},{"@type":"WebSite","@id":"https:\/\/www.arcoabogados.es\/ca#website","url":"https:\/\/www.arcoabogados.es\/ca","name":"ARCO Abogados","description":"Leading Tax and Legal Practice in Spain","publisher":{"@id":"https:\/\/www.arcoabogados.es\/ca#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arcoabogados.es\/ca?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.arcoabogados.es\/ca#organization","name":"ARCO Abogados","url":"https:\/\/www.arcoabogados.es\/ca","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.arcoabogados.es\/ca#\/schema\/logo\/image\/","url":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2023\/07\/arco-logo-160px.png","contentUrl":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2023\/07\/arco-logo-160px.png","width":160,"height":42,"caption":"ARCO Abogados"},"image":{"@id":"https:\/\/www.arcoabogados.es\/ca#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/arcoabogados\/"]},{"@type":"Person","@id":"https:\/\/www.arcoabogados.es\/ca#\/schema\/person\/8c38bf10d19f9bf1eedff598c01ce056","name":"Anna Vivas","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g","caption":"Anna Vivas"}}]}},"_links":{"self":[{"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/posts\/12464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/comments?post=12464"}],"version-history":[{"count":4,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/posts\/12464\/revisions"}],"predecessor-version":[{"id":12486,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/posts\/12464\/revisions\/12486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/media\/12460"}],"wp:attachment":[{"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/media?parent=12464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/categories?post=12464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/tags?post=12464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}