{"id":11626,"date":"2024-07-19T13:15:00","date_gmt":"2024-07-19T11:15:00","guid":{"rendered":"https:\/\/www.arcoabogados.es\/?p=11626"},"modified":"2024-09-17T11:44:35","modified_gmt":"2024-09-17T09:44:35","slug":"alertes-tributaries-%c2%b7-juliol-2024","status":"publish","type":"post","link":"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024","title":{"rendered":"Alertes Tribut\u00e0ries \u00b7 Juliol 2024"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">1. Fiscalitat indirecta de donaci\u00f3 d&#8217;un immoble promogut i arrendat pel donant.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La Direcci\u00f3 General de Tributs (DGT), en la consulta vinculant V0260-24, de 29 de febrer, resol una q\u00fcesti\u00f3 relativa a una persona f\u00edsica que va promoure en el seu moment la construcci\u00f3 d&#8217;un local industrial el dest\u00ed del qual va ser l&#8217;arrendament a un fill seu per al desenvolupament d&#8217;una activitat econ\u00f2mica, havent-se dedu\u00eft les quotes suportades de l&#8217;IVA suportades en la seva construcci\u00f3. Respecte d&#8217;aquest local el propietari es planteja la seva donaci\u00f3 a favor del seu fill, arrendatari d&#8217;aquest, preguntant a la DGT si aquest lliurament tributaria per IVA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En relaci\u00f3 amb aix\u00f2, el Centre Directiu assenyala, en primer lloc, la condici\u00f3 d&#8217;empresari o professional del consultant, estant subjectes a l&#8217;IVA els lliuraments de b\u00e9ns o prestacions de serveis que realitzi en l&#8217;exercici de la seva activitat econ\u00f2mica en el territori d&#8217;aplicaci\u00f3 de l&#8217;impost, de conformitat amb els articles 4 i 5 de la Llei de l&#8217;IVA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quant a la tributaci\u00f3 indirecta de la donaci\u00f3 objecte de consulta, la DGT afirma que estar\u00edem davant un primer lliurament d&#8217;edificaci\u00f3 i, per tant, estaria subjecta i no exempta de l&#8217;IVA, tal com disposa l&#8217;article 20.U.22\u00e8 de la Llei de l&#8217;IVA, tenint present que l&#8217;\u00fanic \u00fas del local des de la seva construcci\u00f3 ha estat el d&#8217;arrendament a favor de la persona que ara ser\u00e0 el seu adquirent per mitj\u00e0 de la donaci\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tipus aplicable de l&#8217;IVA en la indicada operaci\u00f3 a t\u00edtol gratu\u00eft seria el general, el 21% i la base imposable, de donar-se les circumst\u00e0ncies previstes en l&#8217;article 79.Cinc de la Llei de l&#8217;impost, per tractar-se de parts vinculades, seria el valor normal de mercat del ben donat.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2. Tributaci\u00f3 de les rendes obtingudes per una societat en formaci\u00f3.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El Tribunal Suprem, en sent\u00e8ncia de 20 de juny de 2024, aborda la q\u00fcesti\u00f3 de si les societats en formaci\u00f3 han de tributar per l&#8217;Impost de societats (IS)&nbsp;o si, per part seva, han de ser els seus socis els qui tributin per l&#8217;Impost sobre la Renda de les Persones F\u00edsiques (IRPF) mitjan\u00e7ant el r\u00e8gim d&#8217;atribuci\u00f3 de rendes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cas en q\u00fcesti\u00f3 analitza si una societat de responsabilitat limitada, que havia atorgat escriptura de constituci\u00f3, per\u00f2 encara no s&#8217;havia inscrit en el Registre Mercantil, havia de ser considerada subjecte passiu del&nbsp;IS&nbsp;o si, per contra, les rendes generades havien d&#8217;atribuir-se als seus socis en l&#8217;IRPF.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre aquest tema, el TS recorda que, en virtut de l&#8217;article 33 del Text Ref\u00f3s de la Llei de Societats de Capital, la personalitat jur\u00eddica al tipus social triat s&#8217;adquireix amb la inscripci\u00f3 al Registre Mercantil. Aix\u00ed mateix, l&#8217;article 7.1.a) de la Llei de l&#8217;Impost de societats estableix que \u201cseran subjectes passius de l&#8217;impost, quan tinguin la seva resid\u00e8ncia en territori espanyol: les persones jur\u00eddiques, excloses les societats civils que no tinguin objecte mercantil\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per aix\u00f2, la sent\u00e8ncia indicada sost\u00e9 que el legislador atribueix la condici\u00f3 de subjecte passiu del&nbsp;IS&nbsp;a les entitats amb personalitat jur\u00eddica plena, assenyalant que, d&#8217;acord amb la normativa mercantil, \u00e9s la inscripci\u00f3 registral la que atorga a les societats tal condici\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per conseg\u00fcent, en l\u00ednia amb el criteri de l&#8217;Administraci\u00f3, el TS considera que les societats en formaci\u00f3, encara que realitzin activitats econ\u00f2miques i generin ingressos, no adquireixen personalitat jur\u00eddica fins a la seva inscripci\u00f3 en el Registre Mercantil i, per tant, durant aquest per\u00edode, no poden tributar pel&nbsp;IS, de conformitat amb el que es preveu en l&#8217;article 7 de la Llei del&nbsp;IS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Derivat de l&#8217;anterior, en l&#8217;esmentat per\u00edode temporal, les rendes generades per aquesta societat en formaci\u00f3 se subjecten als seus socis en r\u00e8gim d&#8217;atribuci\u00f3 de rendes en l&#8217;IRPF previst en l&#8217;art. 88 de la Llei d&#8217;IRPF.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3. Mesures fiscals contingudes en el Reial decret llei 4\/2024.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Amb la publicaci\u00f3 del Reial decret llei 4\/2024, de 26 de juny, en el BOE del 27 de juny, s&#8217;han prorrogat determinades mesures per a afrontar les conseq\u00fc\u00e8ncies econ\u00f2miques i socials derivades dels conflictes a Ucra\u00efna i Orient Pr\u00f2xim i, aix\u00ed mateix, s&#8217;han adoptat mesures urgents en mat\u00e8ria fiscal, energ\u00e8tica i social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les principals novetats fiscals s\u00f3n les seg\u00fcents.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Impost sobre el Valor Afegit<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Es prorroga fins al 30 de setembre de 2024 el tipus del 5% per a olis de llavors i pastes; a partir de l&#8217;1 d&#8217;octubre, i fins al 31 de desembre, el tipus ser\u00e0 del 7,5% per a olis de llavors i pastes, el 2% per a aliments b\u00e0sics.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es mant\u00e9 al 0% fins al 30 de setembre parteixi pa, farines, llet, formatges, ous, fruites, verdures i oli d&#8217;oliva. En el cas de l&#8217;oli d&#8217;oliva, i amb efectes a partir de l&#8217;1 de gener de 2025, l&#8217;oli oliva ser\u00e0 considerat aliment de primera necessitat, sent el seu tipus impositiu el 4%.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Impost de societats<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Millora de la reserva de capitalitzaci\u00f3: augment de la reducci\u00f3 al 15% -actualment el 10%- i reducci\u00f3 del termini de manteniment a 3 anys -actualment 5 anys.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Llibertat d&#8217;amortitzaci\u00f3 per a vehicles el\u00e8ctrics i infraestructures de rec\u00e0rregues en 2024 i 2025.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Impost sobre la Renda de les Persones F\u00edsiques<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Elevaci\u00f3 del llindar de tributaci\u00f3 al salari m\u00ednim interprofessional, aix\u00f2 \u00e9s, a 15.876 euros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ampliaci\u00f3 a 2024 de la deducci\u00f3 per resid\u00e8ncia a La Palma (Illes Can\u00e0ries).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Llibertat d&#8217;amortitzaci\u00f3 per a aut\u00f2noms en estimaci\u00f3 objectiva.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>IBI e IAE<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Pr\u00f2rroga de beneficis fiscals per a La Palma en 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1. Fiscalitat indirecta de donaci\u00f3 d&#8217;un immoble promogut i arrendat<\/p>\n","protected":false},"author":12,"featured_media":11632,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[381,321],"tags":[],"class_list":["post-11626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alerta-tributaria-ca","category-fiscal-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alertes Tribut\u00e0ries \u00b7 Juliol 2024 - ARCO Abogados<\/title>\n<meta name=\"description\" content=\"1. Fiscalitat indirecta de donaci\u00f3 d&#039;un immoble promogut i arrendat pel donant. La Direcci\u00f3 General de Tributs (DGT), en la consulta vinculant V0260-24,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alertes Tribut\u00e0ries \u00b7 Juliol 2024 - ARCO Abogados\" \/>\n<meta property=\"og:description\" content=\"1. Fiscalitat indirecta de donaci\u00f3 d&#039;un immoble promogut i arrendat pel donant. La Direcci\u00f3 General de Tributs (DGT), en la consulta vinculant V0260-24,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024\" \/>\n<meta property=\"og:site_name\" content=\"ARCO Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-19T11:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-17T09:44:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/07\/standsome-worklifestyle-zY1ZWW1_CqE-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anna Vivas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/alertes-tributaries-%c2%b7-juliol-2024#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/alertes-tributaries-%c2%b7-juliol-2024\"},\"author\":{\"name\":\"Anna Vivas\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#\\\/schema\\\/person\\\/8c38bf10d19f9bf1eedff598c01ce056\"},\"headline\":\"Alertes Tribut\u00e0ries \u00b7 Juliol 2024\",\"datePublished\":\"2024-07-19T11:15:00+00:00\",\"dateModified\":\"2024-09-17T09:44:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/alertes-tributaries-%c2%b7-juliol-2024\"},\"wordCount\":915,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/alertes-tributaries-%c2%b7-juliol-2024#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/standsome-worklifestyle-zY1ZWW1_CqE-unsplash-scaled.jpg\",\"articleSection\":[\"Alerta Tribut\u00e0ria\",\"Fiscal\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/alertes-tributaries-%c2%b7-juliol-2024\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/alertes-tributaries-%c2%b7-juliol-2024\",\"name\":\"Alertes Tribut\u00e0ries \u00b7 Juliol 2024 - ARCO Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/alertes-tributaries-%c2%b7-juliol-2024#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/alertes-tributaries-%c2%b7-juliol-2024#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/standsome-worklifestyle-zY1ZWW1_CqE-unsplash-scaled.jpg\",\"datePublished\":\"2024-07-19T11:15:00+00:00\",\"dateModified\":\"2024-09-17T09:44:35+00:00\",\"description\":\"1. Fiscalitat indirecta de donaci\u00f3 d'un immoble promogut i arrendat pel donant. La Direcci\u00f3 General de Tributs (DGT), en la consulta vinculant V0260-24,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/alertes-tributaries-%c2%b7-juliol-2024#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/alertes-tributaries-%c2%b7-juliol-2024\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/alertes-tributaries-%c2%b7-juliol-2024#primaryimage\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/standsome-worklifestyle-zY1ZWW1_CqE-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/standsome-worklifestyle-zY1ZWW1_CqE-unsplash-scaled.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/alertes-tributaries-%c2%b7-juliol-2024#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\\\/inici\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alertes Tribut\u00e0ries \u00b7 Juliol 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#website\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\",\"name\":\"ARCO Abogados\",\"description\":\"Leading Tax and Legal Practice in Spain\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#organization\",\"name\":\"ARCO Abogados\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/arco-logo-160px.png\",\"contentUrl\":\"https:\\\/\\\/www.arcoabogados.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/arco-logo-160px.png\",\"width\":160,\"height\":42,\"caption\":\"ARCO Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arcoabogados\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arcoabogados.es\\\/ca#\\\/schema\\\/person\\\/8c38bf10d19f9bf1eedff598c01ce056\",\"name\":\"Anna Vivas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g\",\"caption\":\"Anna Vivas\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alertes Tribut\u00e0ries \u00b7 Juliol 2024 - ARCO Abogados","description":"1. Fiscalitat indirecta de donaci\u00f3 d'un immoble promogut i arrendat pel donant. La Direcci\u00f3 General de Tributs (DGT), en la consulta vinculant V0260-24,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024","og_locale":"ca_ES","og_type":"article","og_title":"Alertes Tribut\u00e0ries \u00b7 Juliol 2024 - ARCO Abogados","og_description":"1. Fiscalitat indirecta de donaci\u00f3 d'un immoble promogut i arrendat pel donant. La Direcci\u00f3 General de Tributs (DGT), en la consulta vinculant V0260-24,","og_url":"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024","og_site_name":"ARCO Abogados","article_published_time":"2024-07-19T11:15:00+00:00","article_modified_time":"2024-09-17T09:44:35+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/07\/standsome-worklifestyle-zY1ZWW1_CqE-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Anna Vivas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024#article","isPartOf":{"@id":"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024"},"author":{"name":"Anna Vivas","@id":"https:\/\/www.arcoabogados.es\/ca#\/schema\/person\/8c38bf10d19f9bf1eedff598c01ce056"},"headline":"Alertes Tribut\u00e0ries \u00b7 Juliol 2024","datePublished":"2024-07-19T11:15:00+00:00","dateModified":"2024-09-17T09:44:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024"},"wordCount":915,"publisher":{"@id":"https:\/\/www.arcoabogados.es\/ca#organization"},"image":{"@id":"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024#primaryimage"},"thumbnailUrl":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/07\/standsome-worklifestyle-zY1ZWW1_CqE-unsplash-scaled.jpg","articleSection":["Alerta Tribut\u00e0ria","Fiscal"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024","url":"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024","name":"Alertes Tribut\u00e0ries \u00b7 Juliol 2024 - ARCO Abogados","isPartOf":{"@id":"https:\/\/www.arcoabogados.es\/ca#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024#primaryimage"},"image":{"@id":"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024#primaryimage"},"thumbnailUrl":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/07\/standsome-worklifestyle-zY1ZWW1_CqE-unsplash-scaled.jpg","datePublished":"2024-07-19T11:15:00+00:00","dateModified":"2024-09-17T09:44:35+00:00","description":"1. Fiscalitat indirecta de donaci\u00f3 d'un immoble promogut i arrendat pel donant. La Direcci\u00f3 General de Tributs (DGT), en la consulta vinculant V0260-24,","breadcrumb":{"@id":"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024#primaryimage","url":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/07\/standsome-worklifestyle-zY1ZWW1_CqE-unsplash-scaled.jpg","contentUrl":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2024\/07\/standsome-worklifestyle-zY1ZWW1_CqE-unsplash-scaled.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.arcoabogados.es\/ca\/alertes-tributaries-%c2%b7-juliol-2024#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.arcoabogados.es\/ca\/inici"},{"@type":"ListItem","position":2,"name":"Alertes Tribut\u00e0ries \u00b7 Juliol 2024"}]},{"@type":"WebSite","@id":"https:\/\/www.arcoabogados.es\/ca#website","url":"https:\/\/www.arcoabogados.es\/ca","name":"ARCO Abogados","description":"Leading Tax and Legal Practice in Spain","publisher":{"@id":"https:\/\/www.arcoabogados.es\/ca#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arcoabogados.es\/ca?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.arcoabogados.es\/ca#organization","name":"ARCO Abogados","url":"https:\/\/www.arcoabogados.es\/ca","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.arcoabogados.es\/ca#\/schema\/logo\/image\/","url":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2023\/07\/arco-logo-160px.png","contentUrl":"https:\/\/www.arcoabogados.es\/wp-content\/uploads\/2023\/07\/arco-logo-160px.png","width":160,"height":42,"caption":"ARCO Abogados"},"image":{"@id":"https:\/\/www.arcoabogados.es\/ca#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/arcoabogados\/"]},{"@type":"Person","@id":"https:\/\/www.arcoabogados.es\/ca#\/schema\/person\/8c38bf10d19f9bf1eedff598c01ce056","name":"Anna Vivas","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d1d4a9e66dfc1694889a31d3f542b8b63a7b461cbe343002ed2fa7e3b2722b6?s=96&d=mm&r=g","caption":"Anna Vivas"}}]}},"_links":{"self":[{"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/posts\/11626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/comments?post=11626"}],"version-history":[{"count":1,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/posts\/11626\/revisions"}],"predecessor-version":[{"id":11627,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/posts\/11626\/revisions\/11627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/media\/11632"}],"wp:attachment":[{"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/media?parent=11626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/categories?post=11626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arcoabogados.es\/ca\/wp-json\/wp\/v2\/tags?post=11626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}